{"id":2341,"date":"2016-03-08T13:31:57","date_gmt":"2016-03-08T12:31:57","guid":{"rendered":"http:\/\/www.francais-d-allemagne.eu\/nord\/?p=2341"},"modified":"2017-01-09T12:43:37","modified_gmt":"2017-01-09T11:43:37","slug":"bilan-de-la-rencontre-initiative-emploi-hambourg","status":"publish","type":"post","link":"https:\/\/www.francais-d-allemagne.eu\/nord\/2016\/03\/08\/bilan-de-la-rencontre-initiative-emploi-hambourg\/","title":{"rendered":"Bilan de la rencontre Initiative Emploi Hambourg"},"content":{"rendered":"<p><strong>Quinze personnes se sont retrouv\u00e9es le mercredi 24 f\u00e9vrier \u00e0 l\u2019invitation de l\u2019association Fran\u00e7ais du Monde Hambourg et du conseiller consulaire \u00e9lu Nicolas Stallivieri pour une premi\u00e8re rencontre du groupe de r\u00e9flexion sur l\u2019int\u00e9gration et le d\u00e9veloppement professionnel des Fran\u00e7ais \u00e9tablis \u00e0 Hambourg et en Allemagne du Nord.<\/strong><\/p>\n<p>Apr\u00e8s un tour de table qui a permis de <strong>mettre en \u00e9vidence la diversit\u00e9 des profils et des parcours d\u2019expatriation<\/strong>, notre conseiller consulaire \u00e9lu a pr\u00e9sent\u00e9 de fa\u00e7on succincte les principaux dispositifs francophones pour l\u2019accompagnement et l\u2019orientation dont pouvaient b\u00e9n\u00e9ficier les Fran\u00e7ais \u00e9tablis \u00e0 Hambourg.<\/p>\n<p>Il s\u2019agit principalement du projet franco-allemand pour l\u2019int\u00e9gration sur le march\u00e9 du travail allemand et la formation professionnelle <strong>Emploi-Allemagne<\/strong>, qui a pris le relais, sur une base associative et dans le cadre d\u2019une convention avec l\u2019Ambassade de France, de la mission de service public assur\u00e9e avant leur fermeture en 2009 par les comit\u00e9s consulaires pour l\u2019emploi et la formation professionnelle.<\/p>\n<p>A notre \u00e9chelon de proximit\u00e9, <strong>le conseil consulaire<\/strong> est charg\u00e9 de rendre des avis et de formuler des propositions aupr\u00e8s des institutions fran\u00e7aises pour am\u00e9liorer l\u2019acc\u00e8s \u00e0 l\u2019emploi et la formation professionnelle. Il accompagne ainsi l\u2019administration consulaire dans ses projets et encourage les initiatives visant \u00e0 faire la promotion du <strong>syst\u00e8me fran\u00e7ais de formation professionnelle<\/strong> dont peuvent b\u00e9n\u00e9ficier les Fran\u00e7ais \u00e9tablis en Allemagne du Nord. Il faut savoir que celui-ci a connu une r\u00e9forme de r\u00e9gionalisation effective en 2016 qui n\u2019a toutefois pas modifi\u00e9 pour ses b\u00e9n\u00e9ficiaires \u00e0 l\u2019\u00e9tranger les interlocuteurs aupr\u00e8s desquels ils peuvent s\u2019adresser. Pour Hambourg, il s\u2019agit de la section consulaire de Berlin.<\/p>\n<p>C\u2019est dans le cadre de ce mandat que <strong>notre conseiller consulaire \u00e9lu a voulu initier ce groupe de r\u00e9flexion avec l\u2019aide de Magdal\u00e8ne Levy<\/strong>, une de nos compatriotes mobilis\u00e9e pour l\u2019emploi et \u00e9tablie depuis de longues ann\u00e9es \u00e0 Hambourg, pour faire un \u00e9tat des lieux, identifier les besoins et trouver avec les acteurs locaux les ressources de mener des projets communs pour y r\u00e9pondre au mieux.<\/p>\n<p>Gr\u00e2ce \u00e0 <strong>l\u2019association reconnue d\u2019utilit\u00e9 publique Fran\u00e7ais du Monde Hambourg<\/strong> ce groupe de r\u00e9flexion sera renforc\u00e9 dans sa dimension citoyenne par une nouvelle <a href=\"http:\/\/francais-du-monde-hambourg.com\/cellule-emploi\/\" target=\"_blank\"><strong>Cellule Emploi<\/strong><\/a>.<\/p>\n<p>La Cellule Emploi propose des <strong>permanences Emploi mensuelles<\/strong>, organis\u00e9es avec le soutien de l\u2019institut fran\u00e7ais et assur\u00e9es par deux sp\u00e9cialistes du recrutement international et des questions de formation&nbsp;: <strong>Brigitte B\u00e4hr<\/strong> et <strong>Florence Coantic<\/strong>. Ces permanences gratuites pour celles et ceux qui y feront appel ont pour objectif l\u2019information, l\u2019orientation et l\u2019accompagnement autour des questions li\u00e9es \u00e0 leur projet professionnel ou d\u2019entrepreneur.<\/p>\n<p>Les permanences Emploi permettront aussi de comprendre o\u00f9 et en quoi les actions pour le d\u00e9veloppement professionnel men\u00e9e par notre initiative pourront \u00eatre utiles et efficaces.<\/p>\n<p>La <strong>communaut\u00e9 fran\u00e7aise de Hambourg<\/strong> compte en effet aujourd\u2019hui quelques 5.000 membres, dont 10% \u00e0 15% travaillent dans le secteur a\u00e9ronautique. D\u2019autres travaillent aupr\u00e8s de grandes soci\u00e9t\u00e9s fran\u00e7aises dans le domaine commercial, bancaire, de l\u2019enseignement, du luxe, de la chimie ou des \u00e9nergies renouvelables. La plupart de nos compatriotes vivent dans des familles bi-nationales ou sont eux-m\u00eames franco-allemands et ne connaissent pas de difficult\u00e9s d\u2019int\u00e9gration.<\/p>\n<p>Pour autant, cette situation cache des <strong>r\u00e9alit\u00e9s tr\u00e8s diverses<\/strong> et des situations tr\u00e8s h\u00e9t\u00e9rog\u00e8nes. C\u2019est en particulier le cas des conjoint-e-s d\u2019expatri\u00e9s ou encore de celles et ceux qui cherchent \u00e0 valoriser leurs comp\u00e9tences et leurs parcours acad\u00e9miques fran\u00e7ais, une carri\u00e8re internationale ou \u00e0 se r\u00e9orienter sur le march\u00e9 du travail local.<\/p>\n<p>Enfin, il est \u00e0 noter le nombre croissant de nos compatriotes qui initient des <strong>projets entrepreneuriaux<\/strong>, s\u2019orientent vers un statut de travailleur ind\u00e9pendant ou s\u2019investissent dans les <strong>nouvelles formes de travail, de formation et de cr\u00e9ation <\/strong>: startups, e-commerce, travail collaboratif, groupes de formation et de cr\u00e9ation ind\u00e9pendants, MOOCs\u2026.<\/p>\n<p>La rencontre du groupe de r\u00e9flexion a aussi permis de faire l\u2019inventaire d\u2019un certain nombre de <strong>ressources d\u2019informations francophones<\/strong> qui pourront \u00eatre mises \u00e0 contribution dans le cadre de ce projet et qu\u2019il se propose de restituer et de diffuser notamment sur le site de l\u2019association Fran\u00e7ais du Monde Hambourg.<\/p>\n<p>Le constat a \u00e9galement \u00e9t\u00e9 fait de <strong>l\u2019existence d\u2019acteurs et de structures institutionnelles fran\u00e7aises comme allemandes<\/strong> \u00e0 Hambourg et \u00e0 l\u2019\u00e9chelle de sa m\u00e9tropole, qui pourront rejoindre et contribuer \u00e0 un r\u00e9seau d\u2019aide et d\u2019entraide que nous souhaitons continuer d\u2019animer autour de notre groupe de r\u00e9flexion.<\/p>\n<p>C\u2019est en particulier le cas des autres associations francophones et franco-allemandes de la ville ou de plateformes telles <strong>Caf\u00e9 Comp\u00e9tences<\/strong> \u00e0 l\u2019initiative de Nathalie Brochard et Florence Coantic qui propose un r\u00e9seau de connaissances et de conseils pour acc\u00e9l\u00e9rer et faciliter la r\u00e9alisation de projets.<\/p>\n<p>Le travail de mise en relation de candidats et stagiaires avec les entreprises d\u2019<strong>Arbeit und Leben <\/strong>est \u00e9galement remarquable. Le s\u00e9minaire bilingue franco-allemand d\u2019accompagnement \u00e0 la recherche d\u2019emploi qu\u2019avait organis\u00e9 cette structure \u00e0 la fin de l\u2019ann\u00e9e 2015 a \u00e9t\u00e9 un grand succ\u00e8s qu\u2019il s\u2019agit de renouveler cette ann\u00e9e.<\/p>\n<p>Certains de nos compatriotes, tels Pascal Girardot, qui a co-organis\u00e9 des \u00e9v\u00e8nements autour du film \u00ab&nbsp;<strong>Auf Augenh\u00f6he<\/strong>&nbsp;\u00bb, s\u2019engagent pour renouveler la pratique manag\u00e9riale et encourager le mieux-travailler ensemble.<\/p>\n<p><strong>Dans la perspective d\u2019une prochaine rencontre le 6 juillet 2016 <\/strong>consacr\u00e9e \u00e0 tirer les premiers enseignements de notre cheminement collectif, nous souhaitons d\u2019ici l\u00e0 poursuivre notre travail de mise en r\u00e9seau, d\u2019accompagnement et mettre en place les \u00e9l\u00e9ments d\u2019information que nous voulons mettre \u00e0 disposition de toutes et tous.<\/p>\n<p>N\u2019h\u00e9sitez pas \u00e0 contacter l&rsquo;initiative pour la rejoindre, faire profiter de votre exp\u00e9rience ou de vos id\u00e9es !<\/p>\n<p>emploi@francais-du-monde-hambourg.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quinze personnes se sont retrouv\u00e9es le mercredi 24 f\u00e9vrier \u00e0 l\u2019invitation de l\u2019association Fran\u00e7ais du Monde Hambourg et du conseiller consulaire \u00e9lu Nicolas Stallivieri pour une premi\u00e8re rencontre du groupe de r\u00e9flexion sur l\u2019int\u00e9gration et le d\u00e9veloppement professionnel des Fran\u00e7ais \u00e9tablis \u00e0 Hambourg et en Allemagne du Nord. Apr\u00e8s un tour de table qui a [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2342,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[78],"tags":[51,166],"class_list":["post-2341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-emploi-2","tag-emploi","tag-hambourg"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4ndNg-BL","jetpack_featured_media_url":"https:\/\/www.francais-d-allemagne.eu\/nord\/wp-content\/uploads\/sites\/2\/2016\/03\/emploi-.jpg","_links":{"self":[{"href":"https:\/\/www.francais-d-allemagne.eu\/nord\/wp-json\/wp\/v2\/posts\/2341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.francais-d-allemagne.eu\/nord\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.francais-d-allemagne.eu\/nord\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.francais-d-allemagne.eu\/nord\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.francais-d-allemagne.eu\/nord\/wp-json\/wp\/v2\/comments?post=2341"}],"version-history":[{"count":7,"href":"https:\/\/www.francais-d-allemagne.eu\/nord\/wp-json\/wp\/v2\/posts\/2341\/revisions"}],"predecessor-version":[{"id":2945,"href":"https:\/\/www.francais-d-allemagne.eu\/nord\/wp-json\/wp\/v2\/posts\/2341\/revisions\/2945"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.francais-d-allemagne.eu\/nord\/wp-json\/wp\/v2\/media\/2342"}],"wp:attachment":[{"href":"https:\/\/www.francais-d-allemagne.eu\/nord\/wp-json\/wp\/v2\/media?parent=2341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.francais-d-allemagne.eu\/nord\/wp-json\/wp\/v2\/categories?post=2341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.francais-d-allemagne.eu\/nord\/wp-json\/wp\/v2\/tags?post=2341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}