{"id":2575,"date":"2016-09-02T09:08:12","date_gmt":"2016-09-02T08:08:12","guid":{"rendered":"http:\/\/www.francais-d-allemagne.eu\/nord\/?p=2575"},"modified":"2017-01-08T17:00:29","modified_gmt":"2017-01-08T16:00:29","slug":"la-2e-info-lettre-de-vos-conseillers-consulaires","status":"publish","type":"post","link":"https:\/\/www.francais-d-allemagne.eu\/nord\/2016\/09\/02\/la-2e-info-lettre-de-vos-conseillers-consulaires\/","title":{"rendered":"L&rsquo;info-lettre de vos conseillers consulaires"},"content":{"rendered":"<p>\u00c9lus tous trois conseillers consulaires en mai 2014 pour vous repr\u00e9senter, nous nous attachons \u00e0 remplir notre mandat. Comme nous nous y \u00e9tions engag\u00e9s, nous avons lanc\u00e9 et nous soutenons des projets utiles. Plusieurs d\u00e9placements dans les L\u00e4nder de la circonscription ont \u00e9t\u00e9 effectu\u00e9s.<\/p>\n<p>Nos interlocuteurs directs sont l\u2019ambassadeur et les consuls, dont les services (principalement la section consulaire de Berlin) travaillent pour vous. Nous sommes, de m\u00eame, en relation avec les consuls honoraires de Br\u00eame, Hanovre et Leipzig. Leurs agences consulaires rendent d\u2019appr\u00e9ciables services de proximit\u00e9 \u00a0et compl\u00e8tent les prestations que le r\u00e9seau consulaire ne peut plus assurer seul sur les territoires. Tous sont nos partenaires institutionnels mais nous sommes vos \u00e9lus\u00a0!<\/p>\n<p><strong>Aussi, souhaitons-nous aujourd\u2019hui vous rendre compte de notre action en vous pr\u00e9sentant quelques moments forts de notre mandat.<br \/>\n<\/strong><br \/>\nNous vous remercions encore pour votre confiance et vous souhaitons une bonne rentr\u00e9e!<\/p>\n<p style=\"text-align: justify\"><a title=\"L'INFO-LETTRE\" href=\"http:\/\/url.snd43.ch\/visu-3EA09690-393D-43D7-9D2A-91535D68DE23-782890450-895399-31082016.html\" target=\"_blank\">L&rsquo;INFO-LETTRE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9lus tous trois conseillers consulaires en mai 2014 pour vous repr\u00e9senter, nous nous attachons \u00e0 remplir notre mandat. Comme nous nous y \u00e9tions engag\u00e9s, nous avons lanc\u00e9 et nous soutenons des projets utiles. Plusieurs d\u00e9placements dans les L\u00e4nder de la circonscription ont \u00e9t\u00e9 effectu\u00e9s. Nos interlocuteurs directs sont l\u2019ambassadeur et les consuls, dont les services [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2931,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[82,80],"tags":[90,157],"class_list":["post-2575","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conseil-consulaire-2","category-informations-citoyennes","tag-infolettre","tag-newsletter"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.francais-d-allemagne.eu\/nord\/wp-content\/uploads\/sites\/2\/2016\/09\/infolettre.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4ndNg-Fx","_links":{"self":[{"href":"https:\/\/www.francais-d-allemagne.eu\/nord\/wp-json\/wp\/v2\/posts\/2575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.francais-d-allemagne.eu\/nord\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.francais-d-allemagne.eu\/nord\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.francais-d-allemagne.eu\/nord\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.francais-d-allemagne.eu\/nord\/wp-json\/wp\/v2\/comments?post=2575"}],"version-history":[{"count":3,"href":"https:\/\/www.francais-d-allemagne.eu\/nord\/wp-json\/wp\/v2\/posts\/2575\/revisions"}],"predecessor-version":[{"id":2578,"href":"https:\/\/www.francais-d-allemagne.eu\/nord\/wp-json\/wp\/v2\/posts\/2575\/revisions\/2578"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.francais-d-allemagne.eu\/nord\/wp-json\/wp\/v2\/media\/2931"}],"wp:attachment":[{"href":"https:\/\/www.francais-d-allemagne.eu\/nord\/wp-json\/wp\/v2\/media?parent=2575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.francais-d-allemagne.eu\/nord\/wp-json\/wp\/v2\/categories?post=2575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.francais-d-allemagne.eu\/nord\/wp-json\/wp\/v2\/tags?post=2575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}